
{"id":830449,"date":"2024-06-05T00:01:00","date_gmt":"2024-06-04T18:31:00","guid":{"rendered":"https:\/\/leverageedu.com\/discover\/?p=830449"},"modified":"2024-06-05T00:01:00","modified_gmt":"2024-06-04T18:31:00","slug":"calcutta-university-affiliated-colleges","status":"publish","type":"post","link":"https:\/\/leverageedu.com\/discover\/indian-universities\/calcutta-university-affiliated-colleges\/","title":{"rendered":"List of Calcutta University Affiliated Colleges"},"content":{"rendered":"\n<p>Calcutta University, also known as the University of Calcutta, is one of the oldest and most prestigious universities in India. Established in 1857, it has a rich history and offers a wide range of undergraduate and postgraduate programs. One of the unique features of Calcutta University is its affiliation with numerous colleges across the state of West Bengal. In this blog, we\u2019ll explore what it means to be an affiliated college and highlight some of the notable colleges under Calcutta University.<\/p>\n\n\n\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-list-of-calcutta-university-affiliated-colleges\">List of Calcutta University Affiliated Colleges<\/h2>\n\n\n\n<p>Affiliated colleges are institutions that are not part of the university itself but are recognized by the university to offer its courses. These colleges follow the curriculum set by the university, and their students sit for exams conducted by the university.<br><br>Here is a list of different colleges associated with Calcutta University in different cities:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-kolkata\">Kolkata<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Acharya Girish Chandra Bose College<\/li>\n\n\n\n<li>Acharya Jagadish Chandra Bose College, Kolkata<\/li>\n\n\n\n<li>Anandamohan College, Kolkata, afternoon\/evening college<\/li>\n\n\n\n<li>Asutosh College, day college<\/li>\n\n\n\n<li>Bangabasi College, Kolkata<\/li>\n\n\n\n<li>Bangabasi Evening College, Kolkata<\/li>\n\n\n\n<li>Bangabasi Morning College, Kolkata<\/li>\n\n\n\n<li>Basanti Devi College, Kolkata<\/li>\n\n\n\n<li>Behala College, Kolkata<\/li>\n\n\n\n<li>Bengal Music College, Kolkata<\/li>\n\n\n\n<li>Bethune College, Kolkata<\/li>\n\n\n\n<li>The Bhawanipur Education Society College, Kolkata<\/li>\n\n\n\n<li>Calcutta Girls BT College, Kolkata<\/li>\n\n\n\n<li>Calcutta Girls\u2019 College, Kolkata<\/li>\n\n\n\n<li>Charuchandra College, Kolkata<\/li>\n\n\n\n<li>Chittaranjan College, Kolkata<\/li>\n\n\n\n<li>City College, Kolkata<\/li>\n\n\n\n<li>City College of Commerce and Business Administration, Kolkata<\/li>\n\n\n\n<li>David Hare Training (IASE) College, Kolkata<\/li>\n\n\n\n<li>Debnarayan Shiksha Sansthan, Sonarpur<\/li>\n\n\n\n<li>Deshbandhu College for Girls, Kolkata<\/li>\n\n\n\n<li>Don Bosco College, Park Circus<\/li>\n\n\n\n<li>EI-Bethel College, Rasapunja<\/li>\n\n\n\n<li>Goenka College of Commerce and Business Administration, Kolkata<\/li>\n\n\n\n<li>Gokhale Memorial Girls\u2019 College, Kolkata<\/li>\n\n\n\n<li>Government College of Art & Craft, Kolkata<\/li>\n\n\n\n<li>Government Girls General Degree College, Ekbalpur, Kolkata<\/li>\n\n\n\n<li>Gurudas College, Kolkata<\/li>\n\n\n\n<li>Harimohan Ghose College, Kolkata<\/li>\n\n\n\n<li>Heramba Chandra College, Kolkata, day college<\/li>\n\n\n\n<li>Indian Institute of Social Welfare and Business Management, Kolkata<\/li>\n\n\n\n<li>Institute of Education for Women, Kolkata<\/li>\n\n\n\n<li>Institute of Jute Technology, Kolkata<\/li>\n\n\n\n<li>Jagdish Chandra Basu Sikshak Shikshan Mahavidyalaya, Kolkata<\/li>\n\n\n\n<li>Jogesh Chandra Chaudhuri College, Kolkata<\/li>\n\n\n\n<li>Jogesh Chandra Chaudhuri Law College, Kolkata<\/li>\n\n\n\n<li>Jogamaya Devi College, Kolkata, morning college for women<\/li>\n\n\n\n<li>Kamala Devi Sohanraj Singhvi Jain College of Education, Kolkata<\/li>\n\n\n\n<li>Khudiram Bose Central College, Kolkata<\/li>\n\n\n\n<li>Kidderpore College, Kidderpore<\/li>\n\n\n\n<li>Kishore Bharati Bhagini Nivedita (Co-ed) College, Kolkata<\/li>\n\n\n\n<li>Lady Brabourne College, Kolkata<\/li>\n\n\n\n<li>Loreto College, Kolkata<\/li>\n\n\n\n<li>Maharaja Manindra Chandra College, Kolkata, day college<\/li>\n\n\n\n<li>Maharaja Sris Chandra College, Kolkata, afternoon\/ evening college<\/li>\n\n\n\n<li>Maharani Kasiswari College, Kolkata, morning college for women<\/li>\n\n\n\n<li>Matiaburj College, Kolkata<\/li>\n\n\n\n<li>Maulana Azad College, Kolkata<\/li>\n\n\n\n<li>Milli Al-Ameen College for Girls, Kolkata<\/li>\n\n\n\n<li>Muralidhar Girls\u2019 College, Kolkata<\/li>\n\n\n\n<li>Naba Ballygunge Mahavidyalaya, Kolkata<\/li>\n\n\n\n<li>Netaji Nagar College (Evening), Kolkata<\/li>\n\n\n\n<li>Netaji Nagar College for Women, Kolkata, morning college<\/li>\n\n\n\n<li>Netaji Nagar Day College, Kolkata<\/li>\n\n\n\n<li>New Alipore College, Kolkata<\/li>\n\n\n\n<li>Prafulla Chandra College, Kolkata, afternoon\/ evening college<\/li>\n\n\n\n<li>Rabin Mukherjee College, Kolkata<\/li>\n\n\n\n<li>Rammohan College, Kolkata, morning college for women<\/li>\n\n\n\n<li>Rani Birla Girls\u2019 College, Kolkata<\/li>\n\n\n\n<li>Seth Anandram Jaipuria College, Kolkata<\/li>\n\n\n\n<li>Sammilani Mahavidyalaya, Kolkata<\/li>\n\n\n\n<li>Sammilani Teachers Training College, Barakhola<\/li>\n\n\n\n<li>Sanskrit College, Kolkata<\/li>\n\n\n\n<li>Sarsuna College, Kolkata<\/li>\n\n\n\n<li>Savitri Girls\u2019 College, Kolkata<\/li>\n\n\n\n<li>Scottish Church College, Kolkata<\/li>\n\n\n\n<li>Seth Soorajmull Jalan Girls\u2019 College, Kolkata<\/li>\n\n\n\n<li>Shyambazar Law College, Kolkata<\/li>\n\n\n\n<li>Sivanath Sastri College, Kolkata, morning college for women<\/li>\n\n\n\n<li>Shri Shikshayatan College, Kolkata<\/li>\n\n\n\n<li>Sir Gurudas Mahavidyalaya, Kolkata<\/li>\n\n\n\n<li>Sister Nibedita Government General Degree College for Girls<\/li>\n\n\n\n<li>South Calcutta Girls College, Kolkata<\/li>\n\n\n\n<li>South Calcutta Law College, Kolkata<\/li>\n\n\n\n<li>St. Paul\u2019s Cathedral Mission College, Kolkata<\/li>\n\n\n\n<li>St. Xavier\u2019s College, Kolkata<\/li>\n\n\n\n<li>State Institute of Physical Education For Women, Kolkata<\/li>\n\n\n\n<li>Surendranath College for Women, Kolkata<\/li>\n\n\n\n<li>Surendranath Evening College, Kolkata<\/li>\n\n\n\n<li>Surendra Lal Das Teachers Training College, Ananda Nagar<\/li>\n\n\n\n<li>Surendranath Law College, Kolkata<\/li>\n\n\n\n<li>Surendranath College, Kolkata<\/li>\n\n\n\n<li>Syamaprasad College, Kolkata, afternoon\/ evening college<\/li>\n\n\n\n<li>Taradevi Harakhchand Kankaria Jain College, Kolkata<\/li>\n\n\n\n<li>The Heritage College, Anandapur<\/li>\n\n\n\n<li>Umes Chandra College, Kolkata<\/li>\n\n\n\n<li>Vedanta College, Phoolbagan<\/li>\n\n\n\n<li>Victoria Institution (College), Kolkata<\/li>\n\n\n\n<li>Vidyasagar College for Women, Kolkata<\/li>\n\n\n\n<li>Vidyasagar College, Kolkata<\/li>\n\n\n\n<li>Vidyasagar Evening College, Kolkata<\/li>\n\n\n\n<li>Viharilal College for Home and Social Science, Kolkata<\/li>\n\n\n\n<li>Vijaygarh Jyotish Ray College, Kolkata<\/li>\n\n\n\n<li>Vivekananda College for Women, Kolkata<\/li>\n\n\n\n<li>Vivekananda College, Thakurpukur, Kolkata<\/li>\n\n\n\n<li>Women\u2019s Christian College, Kolkata<\/li>\n\n\n\n<li>Women\u2019s College, Kolkata<\/li>\n<\/ul>\n\n\n\n<p class=\"has-electric-grass-gradient-background has-background\"><strong>Also Read:<\/strong> <a href=\"https:\/\/leverageedu.com\/discover\/indian-universities\/list-of-indian-universities-tie-up-with-foreign-universities\/\"><strong>List of Indian Universities Tie Up with Foreign Universities<\/strong><\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-south-24-pragnas\">South 24 Pragnas<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Al Ameen Memorial Minority College, Baruipur<\/li>\n\n\n\n<li>Bankim Sardar College, Tangrakhali, South 24 Parganas<\/li>\n\n\n\n<li>Baruipur College, Baruipur, South 24 Parganas<\/li>\n\n\n\n<li>Bhangar Mahavidyalaya, Bhangar, South 24 Parganas<\/li>\n\n\n\n<li>Bikash Bharati Law College, Joyrampur, Amtala<\/li>\n\n\n\n<li>Budge Budge College, Budge Budge, South 24 Parganas<\/li>\n\n\n\n<li>Dhola Mahavidyalaya, Dhola, South 24 Parganas<\/li>\n\n\n\n<li>Dhruba Chand Halder College, South 24 Parganas<\/li>\n\n\n\n<li>Dinabandhu Andrews College, Garia, Kolkata<\/li>\n\n\n\n<li>Fakir Chand College, Diamond Harbour, South 24 Parganas<\/li>\n\n\n\n<li>Jibantala Rokeya Mahavidyalaya, Mallikati, South 24 Parganas<\/li>\n\n\n\n<li>K. K. Das College, Garia<\/li>\n\n\n\n<li>L.J.D. College, Punnyahat, PO Saharahat, South 24 Parganas<\/li>\n\n\n\n<li>Kultali Dr. B .R. Ambedkar College, Kultali, South 24 Parganas<\/li>\n\n\n\n<li>Magrahat College, Magrahat, South 24 Parganas<\/li>\n\n\n\n<li>Maheshtala College, Kolkata<\/li>\n\n\n\n<li>Panchur College, South 24 Parganas<\/li>\n\n\n\n<li>Parameswar Mahavidyalaya (B.Ed), South 24 Parganas<\/li>\n\n\n\n<li>Patharpratima Mahavidyalaya, Patharpratima, South 24 Parganas<\/li>\n\n\n\n<li>Rabindra Shiksha Sammilani Law College, Subhashgram, South 24 Parganas<\/li>\n\n\n\n<li>Raidighi B Ed College, Raidighi<\/li>\n\n\n\n<li>Raidighi College, Raidighi, South 24 Parganas<\/li>\n\n\n\n<li>Ramakrishna Mission Blind Boys Academy, Narendrapur<\/li>\n\n\n\n<li>Ramakrishna Mission Residential College, Narendrapur, South 24 Parganas<\/li>\n\n\n\n<li>Sadhan Chandra Mahavidyalaya, Harindanga, South 24 Parganas<\/li>\n\n\n\n<li>Sagar Mahavidyalaya, Harinbari, South 24 Parganas<\/li>\n\n\n\n<li>Saheed Anurup Chandra Mahavidyalaya, Burul, South 24 Parganas<\/li>\n\n\n\n<li>Sarisa B.Ed College, South 24 Parganas<\/li>\n\n\n\n<li>Sonarpur Mahavidyalaya, Kolkata<\/li>\n\n\n\n<li>Shirakole Mahavidyalaya, Sirakol, South 24 Parganas<\/li>\n\n\n\n<li>Sibani Mandal Mahavidyalaya, Namkhana, South 24 Parganas<\/li>\n\n\n\n<li>Sukanta College, Bhangankhali, South 24 Parganas<\/li>\n\n\n\n<li>Sundarban Ashutosh B Ed College for Women, South 24 Parganas<\/li>\n\n\n\n<li>Sundarban Hazi Desarat College, Pathankhali, South 24 Parganas<\/li>\n\n\n\n<li>Sundarban Mahavidyalaya, Kakdwip, South 24 Parganas<\/li>\n\n\n\n<li>Sushil Kar College, Champahati, South 24 Parganas<\/li>\n\n\n\n<li>Vidyanagar College, Charashyamdas,Vidyanagar<\/li>\n<\/ul>\n\n\n\n<p class=\"has-electric-grass-gradient-background has-background\"><strong>Also Read:<\/strong> <a href=\"https:\/\/leverageedu.com\/discover\/indian-universities\/llm-in-calcutta-university\/\"><strong>LLM In Calcutta University<\/strong><\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-howrah-nbsp\">Howrah\u00a0<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Bijoy Krishna Girls\u2019 College, Howrah<\/li>\n\n\n\n<li>Azad Hind Fouz Smriti Mahavidyalaya, Domjur<\/li>\n\n\n\n<li>Bagnan College, Howrah<\/li>\n\n\n\n<li>Dinabandhu Institution, Howrah<\/li>\n\n\n\n<li>Dr. Kanailal Bhattacharya College, Santragachi<\/li>\n\n\n\n<li>Gangabharpur Sikshan Mandir, Howrah<\/li>\n\n\n\n<li>Gangadharpur Mahavidyamandir, Gangadharpur, Howrah<\/li>\n\n\n\n<li>Jaypur Panchanan Roy College, Howrah<\/li>\n\n\n\n<li>Lalbaba College, Howrah<\/li>\n\n\n\n<li>Narasinha Dutt College, Howrah<\/li>\n\n\n\n<li>Panchla Mahavidyalaya, Howrah<\/li>\n\n\n\n<li>Prabhu Jagatbandhu College, Howrah<\/li>\n\n\n\n<li>Puras-Kanpur Haridas Nandi Mahavidyalaya, Kolkata<\/li>\n\n\n\n<li>Ramakrishna Mission Shikshanamandira, Belur, Howrah<\/li>\n\n\n\n<li>Ramakrishna Mission Vidyamandira, Belur, Howrah<\/li>\n\n\n\n<li>Ramsaday College, Amta<\/li>\n\n\n\n<li>Sovarani Memorial College, Jagatballavpur<\/li>\n\n\n\n<li>Shyampur Siddheswari Mahavidyalaya, Ajodhya<\/li>\n\n\n\n<li>Udaynarayanpur Madhabilata Mahavidyalaya, Udaynarayanpur<\/li>\n\n\n\n<li>Uluberia College, Uluberia<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-hoogly\">Hoogly<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Bidhan Chandra College, Rishra, Rishra<\/li>\n\n\n\n<li>George School of Law, Konnagar, Hooghly<\/li>\n\n\n\n<li>Gourmohan Sachin Mondal Mahavidyalaya, Bireswarpur<\/li>\n\n\n\n<li>Mahitosh Nandy Mahavidyalaya, Jangipara<\/li>\n\n\n\n<li>Sree Agrasain College, Liluah<\/li>\n\n\n\n<li>Serampore College, Serampore<\/li>\n\n\n\n<li>Serampore Girls\u2019 College, Serampore<\/li>\n\n\n\n<li>Nabagram Hiralal Paul College, Konnagar<\/li>\n\n\n\n<li>Raja Peary Mohan College, Uttarpara<\/li>\n\n\n\n<li>Swami Niswambalananda Girls\u2019 College, Bhadrakali<\/li>\n\n\n\n<li>Vidyasagar Mahavidyalaya, Masat<\/li>\n<\/ul>\n\n\n\n<p class=\"has-electric-grass-gradient-background has-background\"><strong>Also Read<\/strong>: <a href=\"https:\/\/leverageedu.com\/discover\/indian-universities\/kalinga-institute-of-industrial-technology-kiit\/\"><strong>(KIIT) Kalinga Institute of Industrial Technology<\/strong><\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-faqs\">FAQs<\/h2>\n\n\n\n<div class=\"schema-faq wp-block-yoast-faq-block\"><div class=\"schema-faq-section\" id=\"faq-question-1717568851919\"><strong class=\"schema-faq-question\">How many colleges are affiliated with Calcutta University?<\/strong> <p class=\"schema-faq-answer\">According to the official website, there are 151 undergraduate colleges affiliated with Calcutta University. Other than these 151 colleges, there are 16 institutes affiliated with the university.<\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1717568855577\"><strong class=\"schema-faq-question\">Is Calcutta University a private or public university?<\/strong> <p class=\"schema-faq-answer\">Calcutta University is a public state university.<\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1717568856650\"><strong class=\"schema-faq-question\">Which college is best under the Calcutta university?<\/strong> <p class=\"schema-faq-answer\">The best college under Calcutta University is Vijaygarh Jyotish Ray College.<\/p> <\/div> <\/div>\n\n\n\n<p class=\"has-text-align-center has-vivid-red-color has-text-color has-link-color wp-elements-d851cef9692c6e162610b220d8c10a79\"><strong>RELATED POSTS<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table><tbody><tr><td><a href=\"https:\/\/leverageedu.com\/discover\/indian-universities\/ignou-bsc-nursing-admission\/\"><strong>IGNOU BSc Nursing Admission 2024 (Post Basic)<\/strong><\/a><\/td><td><a href=\"https:\/\/leverageedu.com\/discover\/indian-universities\/ignou-ma-sociology-admission\/\"><strong>IGNOU MA Sociology Admission<\/strong><\/a><\/td><\/tr><tr><td><a href=\"https:\/\/leverageedu.com\/discover\/indian-universities\/ignou-ma-history-admission\/\"><strong>IGNOU MA History Admission<\/strong><\/a><\/td><td><a href=\"https:\/\/leverageedu.com\/discover\/indian-universities\/ignou-m-tech-admission\/\"><strong>IGNOU M Tech Admission<\/strong><\/a><\/td><\/tr><tr><td><a href=\"https:\/\/leverageedu.com\/discover\/indian-universities\/ignou-ma-psychology-admission\/\"><strong>IGNOU MA Psychology Admission<\/strong><\/a><\/td><td><a href=\"https:\/\/leverageedu.com\/discover\/indian-universities\/ignou-admissions-and-help\/ignou-exam-centres\/\"><strong>IGNOU Exam Centres List<\/strong><\/a><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>This was all about the <strong><em>\u201cCalcutta University Affiliated Colleges\u201d<\/em><\/strong>. For more such informative blogs, check out our<strong> <\/strong><a href=\"https:\/\/leverageedu.com\/discover\/category\/study-in-india\/indian-universities\/\"><strong>Indian University<\/strong><\/a> page.<\/p>\n","protected":false},"excerpt":{"rendered":"Calcutta University, also known as the University of Calcutta, is one of the oldest and most prestigious universities&hellip;\n","protected":false},"author":66,"featured_media":830462,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"editor_notices":[],"footnotes":""},"categories":[370],"tags":[],"class_list":{"0":"post-830449","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-indian-universities"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>List of Calcutta University Affiliated Colleges | Leverage Edu Discover<\/title>\n<meta name=\"description\" content=\"In this blog, we&#039;ll explore what it means to be an affiliated college and highlight some of the notable colleges under Calcutta University.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/leverageedu.com\/discover\/indian-universities\/calcutta-university-affiliated-colleges\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"List of Calcutta University Affiliated Colleges\" \/>\n<meta property=\"og:description\" content=\"In this blog, we&#039;ll explore what it means to be an affiliated college and highlight some of the notable colleges under Calcutta University.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/leverageedu.com\/discover\/indian-universities\/calcutta-university-affiliated-colleges\/\" \/>\n<meta property=\"og:site_name\" content=\"Leverage Edu Discover\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-04T18:31:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blogassets.leverageedu.com\/media\/uploads\/sites\/9\/2024\/06\/14123607\/Calcutta-University-Affiliated-Colleges.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Simran Popli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Simran Popli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"List of Calcutta University Affiliated Colleges | Leverage Edu Discover","description":"In this blog, we'll explore what it means to be an affiliated college and highlight some of the notable colleges under Calcutta University.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/leverageedu.com\/discover\/indian-universities\/calcutta-university-affiliated-colleges\/","og_locale":"en_US","og_type":"article","og_title":"List of Calcutta University Affiliated Colleges","og_description":"In this blog, we'll explore what it means to be an affiliated college and highlight some of the notable colleges under Calcutta University.","og_url":"https:\/\/leverageedu.com\/discover\/indian-universities\/calcutta-university-affiliated-colleges\/","og_site_name":"Leverage Edu Discover","article_published_time":"2024-06-04T18:31:00+00:00","og_image":[{"width":1024,"height":640,"url":"https:\/\/blogassets.leverageedu.com\/media\/uploads\/sites\/9\/2024\/06\/14123607\/Calcutta-University-Affiliated-Colleges.png","type":"image\/png"}],"author":"Simran Popli","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Simran Popli","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/leverageedu.com\/discover\/indian-universities\/calcutta-university-affiliated-colleges\/#article","isPartOf":{"@id":"https:\/\/leverageedu.com\/discover\/indian-universities\/calcutta-university-affiliated-colleges\/"},"author":{"name":"Simran Popli","@id":"https:\/\/leverageedu.com\/discover\/#\/schema\/person\/ab563bf3140884aa49fcdfbc536acfa0"},"headline":"List of Calcutta University Affiliated Colleges","datePublished":"2024-06-04T18:31:00+00:00","mainEntityOfPage":{"@id":"https:\/\/leverageedu.com\/discover\/indian-universities\/calcutta-university-affiliated-colleges\/"},"wordCount":1133,"commentCount":0,"image":{"@id":"https:\/\/leverageedu.com\/discover\/indian-universities\/calcutta-university-affiliated-colleges\/#primaryimage"},"thumbnailUrl":"https:\/\/blogassets.leverageedu.com\/media\/uploads\/sites\/9\/2024\/06\/14123607\/Calcutta-University-Affiliated-Colleges.png","articleSection":["Indian Universities"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/leverageedu.com\/discover\/indian-universities\/calcutta-university-affiliated-colleges\/#respond"]}]},{"@type":["WebPage","FAQPage"],"@id":"https:\/\/leverageedu.com\/discover\/indian-universities\/calcutta-university-affiliated-colleges\/","url":"https:\/\/leverageedu.com\/discover\/indian-universities\/calcutta-university-affiliated-colleges\/","name":"List of Calcutta University Affiliated Colleges | Leverage Edu Discover","isPartOf":{"@id":"https:\/\/leverageedu.com\/discover\/#website"},"primaryImageOfPage":{"@id":"https:\/\/leverageedu.com\/discover\/indian-universities\/calcutta-university-affiliated-colleges\/#primaryimage"},"image":{"@id":"https:\/\/leverageedu.com\/discover\/indian-universities\/calcutta-university-affiliated-colleges\/#primaryimage"},"thumbnailUrl":"https:\/\/blogassets.leverageedu.com\/media\/uploads\/sites\/9\/2024\/06\/14123607\/Calcutta-University-Affiliated-Colleges.png","datePublished":"2024-06-04T18:31:00+00:00","author":{"@id":"https:\/\/leverageedu.com\/discover\/#\/schema\/person\/ab563bf3140884aa49fcdfbc536acfa0"},"description":"In this blog, we'll explore what it means to be an affiliated college and highlight some of the notable colleges under Calcutta University.","breadcrumb":{"@id":"https:\/\/leverageedu.com\/discover\/indian-universities\/calcutta-university-affiliated-colleges\/#breadcrumb"},"mainEntity":[{"@id":"https:\/\/leverageedu.com\/discover\/indian-universities\/calcutta-university-affiliated-colleges\/#faq-question-1717568851919"},{"@id":"https:\/\/leverageedu.com\/discover\/indian-universities\/calcutta-university-affiliated-colleges\/#faq-question-1717568855577"},{"@id":"https:\/\/leverageedu.com\/discover\/indian-universities\/calcutta-university-affiliated-colleges\/#faq-question-1717568856650"}],"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/leverageedu.com\/discover\/indian-universities\/calcutta-university-affiliated-colleges\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/leverageedu.com\/discover\/indian-universities\/calcutta-university-affiliated-colleges\/#primaryimage","url":"https:\/\/blogassets.leverageedu.com\/media\/uploads\/sites\/9\/2024\/06\/14123607\/Calcutta-University-Affiliated-Colleges.png","contentUrl":"https:\/\/blogassets.leverageedu.com\/media\/uploads\/sites\/9\/2024\/06\/14123607\/Calcutta-University-Affiliated-Colleges.png","width":1024,"height":640,"caption":"Calcutta University Affiliated Colleges"},{"@type":"BreadcrumbList","@id":"https:\/\/leverageedu.com\/discover\/indian-universities\/calcutta-university-affiliated-colleges\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/leverageedu.com\/discover\/"},{"@type":"ListItem","position":2,"name":"List of Calcutta University Affiliated Colleges"}]},{"@type":"WebSite","@id":"https:\/\/leverageedu.com\/discover\/#website","url":"https:\/\/leverageedu.com\/discover\/","name":"Leverage Edu Discover","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/leverageedu.com\/discover\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/leverageedu.com\/discover\/#\/schema\/person\/ab563bf3140884aa49fcdfbc536acfa0","name":"Simran Popli","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/62dd7fe1176cecbe13eb577cde5e4a5c404413ce803d7d507bf78000cee1cf03?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/62dd7fe1176cecbe13eb577cde5e4a5c404413ce803d7d507bf78000cee1cf03?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/62dd7fe1176cecbe13eb577cde5e4a5c404413ce803d7d507bf78000cee1cf03?s=96&d=mm&r=g","caption":"Simran Popli"},"description":"An avid observer and a creative content marketer. With an experience of 1.5 years as a content writer in different industries. Patient, Vivacious and a Great Leader are the best adjectives that can describe her personality.","sameAs":["https:\/\/www.linkedin.com\/in\/simran-popli-469637197\/"],"url":"https:\/\/leverageedu.com\/discover\/author\/simran\/"},{"@type":"Question","@id":"https:\/\/leverageedu.com\/discover\/indian-universities\/calcutta-university-affiliated-colleges\/#faq-question-1717568851919","position":1,"url":"https:\/\/leverageedu.com\/discover\/indian-universities\/calcutta-university-affiliated-colleges\/#faq-question-1717568851919","name":"How many colleges are affiliated with Calcutta University?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"According to the official website, there are 151 undergraduate colleges affiliated with Calcutta University. Other than these 151 colleges, there are 16 institutes affiliated with the university.","inLanguage":"en-US"},"inLanguage":"en-US"},{"@type":"Question","@id":"https:\/\/leverageedu.com\/discover\/indian-universities\/calcutta-university-affiliated-colleges\/#faq-question-1717568855577","position":2,"url":"https:\/\/leverageedu.com\/discover\/indian-universities\/calcutta-university-affiliated-colleges\/#faq-question-1717568855577","name":"Is Calcutta University a private or public university?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"Calcutta University is a public state university.","inLanguage":"en-US"},"inLanguage":"en-US"},{"@type":"Question","@id":"https:\/\/leverageedu.com\/discover\/indian-universities\/calcutta-university-affiliated-colleges\/#faq-question-1717568856650","position":3,"url":"https:\/\/leverageedu.com\/discover\/indian-universities\/calcutta-university-affiliated-colleges\/#faq-question-1717568856650","name":"Which college is best under the Calcutta university?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"The best college under Calcutta University is Vijaygarh Jyotish Ray College.","inLanguage":"en-US"},"inLanguage":"en-US"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/leverageedu.com\/discover\/wp-json\/wp\/v2\/posts\/830449","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leverageedu.com\/discover\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/leverageedu.com\/discover\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/leverageedu.com\/discover\/wp-json\/wp\/v2\/users\/66"}],"replies":[{"embeddable":true,"href":"https:\/\/leverageedu.com\/discover\/wp-json\/wp\/v2\/comments?post=830449"}],"version-history":[{"count":0,"href":"https:\/\/leverageedu.com\/discover\/wp-json\/wp\/v2\/posts\/830449\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/leverageedu.com\/discover\/wp-json\/wp\/v2\/media\/830462"}],"wp:attachment":[{"href":"https:\/\/leverageedu.com\/discover\/wp-json\/wp\/v2\/media?parent=830449"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/leverageedu.com\/discover\/wp-json\/wp\/v2\/categories?post=830449"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/leverageedu.com\/discover\/wp-json\/wp\/v2\/tags?post=830449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}